{"id":72639,"date":"2022-06-15T23:00:00","date_gmt":"2022-06-15T21:00:00","guid":{"rendered":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/morges\/pour-plus-de-durabilite-et-de-transparence-pour-les-etablissements-saisonniers-copy"},"modified":"2022-06-29T11:30:11","modified_gmt":"2022-06-29T09:30:11","slug":"de-la-verdure-a-la-place-des-toitures","status":"publish","type":"post","link":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures","title":{"rendered":"De la verdure \u00e0 la place des toitures"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":44,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[415,396],"tags":[],"class_list":["post-72639","post","type-post","status-publish","format-standard","hentry","category-interventions","category-morges"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures\" \/>\n<meta property=\"og:site_name\" content=\"Les Vert\u00b7e\u00b7s du district de Morges\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-15T21:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T09:30:11+00:00\" \/>\n<meta name=\"author\" content=\"Antoni Jashari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antoni Jashari\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures\"},\"author\":{\"name\":\"Antoni Jashari\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/#\\\/schema\\\/person\\\/a91762c5ae657c4950033e7776f66bbb\"},\"headline\":\"De la verdure \u00e0 la place des toitures\",\"datePublished\":\"2022-06-15T21:00:00+00:00\",\"dateModified\":\"2022-06-29T09:30:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures\"},\"wordCount\":7,\"articleSection\":[\"Interventions\",\"Morges\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures\",\"name\":\"De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/#website\"},\"datePublished\":\"2022-06-15T21:00:00+00:00\",\"dateModified\":\"2022-06-29T09:30:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/#\\\/schema\\\/person\\\/a91762c5ae657c4950033e7776f66bbb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/interventions\\\/de-la-verdure-a-la-place-des-toitures#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interventions\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/blog\\\/category\\\/interventions\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"De la verdure \u00e0 la place des toitures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/#website\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/\",\"name\":\"Les Vert\u00b7e\u00b7s du district de Morges\",\"description\":\"Les Vert\u00b7e\u00b7s du district de Morges\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/morges\\\/#\\\/schema\\\/person\\\/a91762c5ae657c4950033e7776f66bbb\",\"name\":\"Antoni Jashari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g\",\"caption\":\"Antoni Jashari\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures","og_locale":"fr_FR","og_type":"article","og_title":"De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges","og_url":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures","og_site_name":"Les Vert\u00b7e\u00b7s du district de Morges","article_published_time":"2022-06-15T21:00:00+00:00","article_modified_time":"2022-06-29T09:30:11+00:00","author":"Antoni Jashari","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Antoni Jashari"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures#article","isPartOf":{"@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures"},"author":{"name":"Antoni Jashari","@id":"https:\/\/vert-e-s-vd.ch\/morges\/#\/schema\/person\/a91762c5ae657c4950033e7776f66bbb"},"headline":"De la verdure \u00e0 la place des toitures","datePublished":"2022-06-15T21:00:00+00:00","dateModified":"2022-06-29T09:30:11+00:00","mainEntityOfPage":{"@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures"},"wordCount":7,"articleSection":["Interventions","Morges"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures","url":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures","name":"De la verdure \u00e0 la place des toitures - Les Vert\u00b7e\u00b7s du district de Morges","isPartOf":{"@id":"https:\/\/vert-e-s-vd.ch\/morges\/#website"},"datePublished":"2022-06-15T21:00:00+00:00","dateModified":"2022-06-29T09:30:11+00:00","author":{"@id":"https:\/\/vert-e-s-vd.ch\/morges\/#\/schema\/person\/a91762c5ae657c4950033e7776f66bbb"},"breadcrumb":{"@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/interventions\/de-la-verdure-a-la-place-des-toitures#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vert-e-s-vd.ch\/morges\/"},{"@type":"ListItem","position":2,"name":"Interventions","item":"https:\/\/vert-e-s-vd.ch\/morges\/blog\/category\/interventions"},{"@type":"ListItem","position":3,"name":"De la verdure \u00e0 la place des toitures"}]},{"@type":"WebSite","@id":"https:\/\/vert-e-s-vd.ch\/morges\/#website","url":"https:\/\/vert-e-s-vd.ch\/morges\/","name":"Les Vert\u00b7e\u00b7s du district de Morges","description":"Les Vert\u00b7e\u00b7s du district de Morges","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vert-e-s-vd.ch\/morges\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/vert-e-s-vd.ch\/morges\/#\/schema\/person\/a91762c5ae657c4950033e7776f66bbb","name":"Antoni Jashari","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/513d4c958a144cb7aa52daf9126602ece1460eadab515216db5047fd87cc302e?s=96&d=mm&r=g","caption":"Antoni Jashari"}}]}},"_links":{"self":[{"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/posts\/72639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/comments?post=72639"}],"version-history":[{"count":3,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/posts\/72639\/revisions"}],"predecessor-version":[{"id":72649,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/posts\/72639\/revisions\/72649"}],"wp:attachment":[{"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/media?parent=72639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/categories?post=72639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/morges\/wp-json\/wp\/v2\/tags?post=72639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}