{"id":71186,"date":"2020-12-09T20:23:40","date_gmt":"2020-12-09T19:23:40","guid":{"rendered":"https:\/\/web.vert-e-s-vd.ch\/lavaux-oron\/communes\/pully-copy"},"modified":"2026-07-04T22:53:01","modified_gmt":"2026-07-04T20:53:01","slug":"savigny","status":"publish","type":"page","link":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny","title":{"rendered":"Nos \u00e9lu.e.s et leurs interventions"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":74633,"parent":11,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-71186","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny\" \/>\n<meta property=\"og:site_name\" content=\"Les VERT.E.S de Lavaux-Oron\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-04T20:53:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-content\/uploads\/sites\/10\/2025\/12\/savigny-9-12-2025-1200x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny\",\"name\":\"Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/12\\\/savigny-9-12-2025-scaled.jpg\",\"datePublished\":\"2020-12-09T19:23:40+00:00\",\"dateModified\":\"2026-07-04T20:53:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny#primaryimage\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/12\\\/savigny-9-12-2025-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2025\\\/12\\\/savigny-9-12-2025-scaled.jpg\",\"width\":2560,\"height\":1260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\\\/savigny#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Vert\u00b7e\u00b7s dans les communes\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/communes\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nos \u00e9lu.e.s et leurs interventions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/#website\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/\",\"name\":\"Les VERT.E.S de Lavaux-Oron\",\"description\":\"Une longueur d&#039;avance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lavaux-oron\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny","og_locale":"fr_FR","og_type":"article","og_title":"Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron","og_url":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny","og_site_name":"Les VERT.E.S de Lavaux-Oron","article_modified_time":"2026-07-04T20:53:01+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-content\/uploads\/sites\/10\/2025\/12\/savigny-9-12-2025-1200x630.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny","url":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny","name":"Nos \u00e9lu.e.s et leurs interventions - Les VERT.E.S de Lavaux-Oron","isPartOf":{"@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny#primaryimage"},"image":{"@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny#primaryimage"},"thumbnailUrl":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-content\/uploads\/sites\/10\/2025\/12\/savigny-9-12-2025-scaled.jpg","datePublished":"2020-12-09T19:23:40+00:00","dateModified":"2026-07-04T20:53:01+00:00","breadcrumb":{"@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny#primaryimage","url":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-content\/uploads\/sites\/10\/2025\/12\/savigny-9-12-2025-scaled.jpg","contentUrl":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-content\/uploads\/sites\/10\/2025\/12\/savigny-9-12-2025-scaled.jpg","width":2560,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes\/savigny#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/"},{"@type":"ListItem","position":2,"name":"Les Vert\u00b7e\u00b7s dans les communes","item":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/communes"},{"@type":"ListItem","position":3,"name":"Nos \u00e9lu.e.s et leurs interventions"}]},{"@type":"WebSite","@id":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/#website","url":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/","name":"Les VERT.E.S de Lavaux-Oron","description":"Une longueur d&#039;avance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/pages\/71186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/comments?post=71186"}],"version-history":[{"count":107,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/pages\/71186\/revisions"}],"predecessor-version":[{"id":75782,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/pages\/71186\/revisions\/75782"}],"up":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/pages\/11"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/media\/74633"}],"wp:attachment":[{"href":"https:\/\/vert-e-s-vd.ch\/lavaux-oron\/wp-json\/wp\/v2\/media?parent=71186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}