{"id":75515,"date":"2025-06-15T15:49:28","date_gmt":"2025-06-15T13:49:28","guid":{"rendered":"https:\/\/vert-e-s-vd.ch\/lausanne\/?p=75515"},"modified":"2025-06-19T15:59:41","modified_gmt":"2025-06-19T13:59:41","slug":"police-de-proximite","status":"publish","type":"post","link":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite","title":{"rendered":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":75520,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[404,655],"tags":[356,403,327,454],"class_list":["post-75515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intervention-communale","category-marlyse-audergon","tag-qualite-de-vie","tag-quartiers","tag-securite","tag-social"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite\" \/>\n<meta property=\"og:site_name\" content=\"Les VERT\u00b7E\u00b7S lausannois\u00b7es\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-15T13:49:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T13:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-1200x630-c-center.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"anne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"anne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite\"},\"author\":{\"name\":\"anne\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/#\\\/schema\\\/person\\\/37417f96e39e515a5b87cd69a2e0a9b9\"},\"headline\":\"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires\",\"datePublished\":\"2025-06-15T13:49:28+00:00\",\"dateModified\":\"2025-06-19T13:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite\"},\"wordCount\":10,\"image\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Marlyse_Audergon-2-web-scaled.jpg\",\"keywords\":[\"qualit\u00e9 de vie\",\"quartiers\",\"s\u00e9curit\u00e9\",\"social\"],\"articleSection\":[\"Intervention communale\",\"Marlyse Audergon\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite\",\"name\":\"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Marlyse_Audergon-2-web-scaled.jpg\",\"datePublished\":\"2025-06-15T13:49:28+00:00\",\"dateModified\":\"2025-06-19T13:59:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/#\\\/schema\\\/person\\\/37417f96e39e515a5b87cd69a2e0a9b9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#primaryimage\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Marlyse_Audergon-2-web-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Marlyse_Audergon-2-web-scaled.jpg\",\"width\":2560,\"height\":1715,\"caption\":\"Lausanne, le 4 decembre 2020, Marlyse Audergon, candidate au conseil communal avec les Verts Lausannois. Portrait studio. \u00a9 Francesca Palazzi - les Verts lausannois\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/blog\\\/intervention-communale\\\/police-de-proximite#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda\",\"item\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne?post_type=tribe_events&tribe_event_display=list#menu-item-70603\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/#website\",\"url\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/\",\"name\":\"Les VERT\u00b7E\u00b7S lausannois\u00b7es\",\"description\":\"Une longueur d\u2019avance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vert-e-s-vd.ch\\\/lausanne\\\/#\\\/schema\\\/person\\\/37417f96e39e515a5b87cd69a2e0a9b9\",\"name\":\"anne\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g\",\"caption\":\"anne\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite","og_locale":"fr_FR","og_type":"article","og_title":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es","og_url":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite","og_site_name":"Les VERT\u00b7E\u00b7S lausannois\u00b7es","article_published_time":"2025-06-15T13:49:28+00:00","article_modified_time":"2025-06-19T13:59:41+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-1200x630-c-center.jpg","type":"image\/jpeg"}],"author":"anne","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"anne","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#article","isPartOf":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite"},"author":{"name":"anne","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/#\/schema\/person\/37417f96e39e515a5b87cd69a2e0a9b9"},"headline":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires","datePublished":"2025-06-15T13:49:28+00:00","dateModified":"2025-06-19T13:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite"},"wordCount":10,"image":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#primaryimage"},"thumbnailUrl":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-scaled.jpg","keywords":["qualit\u00e9 de vie","quartiers","s\u00e9curit\u00e9","social"],"articleSection":["Intervention communale","Marlyse Audergon"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite","url":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite","name":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires - Les VERT\u00b7E\u00b7S lausannois\u00b7es","isPartOf":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#primaryimage"},"image":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#primaryimage"},"thumbnailUrl":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-scaled.jpg","datePublished":"2025-06-15T13:49:28+00:00","dateModified":"2025-06-19T13:59:41+00:00","author":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/#\/schema\/person\/37417f96e39e515a5b87cd69a2e0a9b9"},"breadcrumb":{"@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#primaryimage","url":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-scaled.jpg","contentUrl":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-content\/uploads\/sites\/7\/2025\/06\/Marlyse_Audergon-2-web-scaled.jpg","width":2560,"height":1715,"caption":"Lausanne, le 4 decembre 2020, Marlyse Audergon, candidate au conseil communal avec les Verts Lausannois. Portrait studio. \u00a9 Francesca Palazzi - les Verts lausannois"},{"@type":"BreadcrumbList","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/blog\/intervention-communale\/police-de-proximite#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vert-e-s-vd.ch\/lausanne\/"},{"@type":"ListItem","position":2,"name":"Agenda","item":"https:\/\/vert-e-s-vd.ch\/lausanne?post_type=tribe_events&tribe_event_display=list#menu-item-70603"},{"@type":"ListItem","position":3,"name":"Renforcement de la police de proximit\u00e9 et des \u00e9quipes socio-sanitaires"}]},{"@type":"WebSite","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/#website","url":"https:\/\/vert-e-s-vd.ch\/lausanne\/","name":"Les VERT\u00b7E\u00b7S lausannois\u00b7es","description":"Une longueur d\u2019avance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vert-e-s-vd.ch\/lausanne\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/vert-e-s-vd.ch\/lausanne\/#\/schema\/person\/37417f96e39e515a5b87cd69a2e0a9b9","name":"anne","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0570858af84b31d095da3690f5a9966acd8cb2fe533763d24c6510190b6cd0ec?s=96&d=mm&r=g","caption":"anne"}}]}},"_links":{"self":[{"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/posts\/75515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/comments?post=75515"}],"version-history":[{"count":9,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/posts\/75515\/revisions"}],"predecessor-version":[{"id":75525,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/posts\/75515\/revisions\/75525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/media\/75520"}],"wp:attachment":[{"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/media?parent=75515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/categories?post=75515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vert-e-s-vd.ch\/lausanne\/wp-json\/wp\/v2\/tags?post=75515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}